{"id":28549,"date":"2025-12-30T12:14:00","date_gmt":"2025-12-30T11:14:00","guid":{"rendered":"https:\/\/nataliaferre.com\/?p=28549"},"modified":"2026-01-28T10:32:38","modified_gmt":"2026-01-28T09:32:38","slug":"lo-safreig","status":"publish","type":"post","link":"https:\/\/nataliaferre.com\/es\/lo-safreig\/","title":{"rendered":"Lo Safreig. El Masroig, Els  Rentadors"},"content":{"rendered":"\n<p>Esta exposici\u00f3n habla de las complicidades que se creaban entre las mujeres en un espacio tan p\u00fablico, y al mismo tiempo tan \u00edntimo, como eran los lavaderos.<\/p>\n\n\n\n<p>Este montaje pretende dar valor a todos estos sitios hist\u00f3ricos de los nuestros pueblos, que fueron esenciales en su momento, y que es necesario<br>preservar.<\/p>\n\n\n\n<p>El Masroig, del 12 de octubre al 12 de diciembre, Domingos de 11:30 a 14:00<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"760\" height=\"1140\" data-id=\"28996\" src=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6534-I-760x1140.jpg\" alt=\"\" class=\"wp-image-28996\" srcset=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6534-I-760x1140.jpg 760w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6534-I-427x640.jpg 427w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6534-I-320x480.jpg 320w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6534-I-768x1152.jpg 768w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6534-I-1024x1536.jpg 1024w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6534-I-1365x2048.jpg 1365w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6534-I-960x1440.jpg 960w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6534-I-640x960.jpg 640w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6534-I-scaled.jpg 1707w\" sizes=\"(max-width: 760px) 100vw, 760px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"760\" height=\"1140\" data-id=\"28993\" src=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6488-I-760x1140.jpg\" alt=\"\" class=\"wp-image-28993\" srcset=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6488-I-760x1140.jpg 760w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6488-I-427x640.jpg 427w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6488-I-320x480.jpg 320w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6488-I-768x1152.jpg 768w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6488-I-1024x1536.jpg 1024w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6488-I-1365x2048.jpg 1365w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6488-I-960x1440.jpg 960w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6488-I-640x960.jpg 640w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6488-I-scaled.jpg 1707w\" sizes=\"(max-width: 760px) 100vw, 760px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"760\" height=\"1140\" data-id=\"29005\" src=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6723-I-760x1140.jpg\" alt=\"\" class=\"wp-image-29005\" srcset=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6723-I-760x1140.jpg 760w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6723-I-427x640.jpg 427w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6723-I-320x480.jpg 320w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6723-I-768x1152.jpg 768w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6723-I-1024x1536.jpg 1024w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6723-I-1365x2048.jpg 1365w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6723-I-960x1440.jpg 960w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6723-I-640x960.jpg 640w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6723-I-scaled.jpg 1706w\" sizes=\"(max-width: 760px) 100vw, 760px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"760\" height=\"1140\" data-id=\"29008\" src=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6737-I-760x1140.jpg\" alt=\"\" class=\"wp-image-29008\" srcset=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6737-I-760x1140.jpg 760w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6737-I-427x640.jpg 427w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6737-I-320x480.jpg 320w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6737-I-768x1152.jpg 768w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6737-I-1024x1536.jpg 1024w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6737-I-1366x2048.jpg 1366w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6737-I-960x1440.jpg 960w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6737-I-640x960.jpg 640w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6737-I-scaled.jpg 1707w\" sizes=\"(max-width: 760px) 100vw, 760px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"760\" height=\"1140\" data-id=\"29037\" src=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6418-I-760x1140.jpg\" alt=\"\" class=\"wp-image-29037\" srcset=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6418-I-760x1140.jpg 760w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6418-I-427x640.jpg 427w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6418-I-320x480.jpg 320w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6418-I-768x1152.jpg 768w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6418-I-1024x1536.jpg 1024w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6418-I-1365x2048.jpg 1365w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6418-I-960x1440.jpg 960w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6418-I-640x960.jpg 640w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6418-I-scaled.jpg 1707w\" sizes=\"(max-width: 760px) 100vw, 760px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"760\" height=\"1140\" data-id=\"29034\" src=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6406-I-760x1140.jpg\" alt=\"\" class=\"wp-image-29034\" srcset=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6406-I-760x1140.jpg 760w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6406-I-427x640.jpg 427w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6406-I-320x480.jpg 320w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6406-I-768x1152.jpg 768w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6406-I-1024x1536.jpg 1024w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6406-I-1365x2048.jpg 1365w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6406-I-960x1440.jpg 960w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6406-I-640x960.jpg 640w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6406-I-scaled.jpg 1707w\" sizes=\"(max-width: 760px) 100vw, 760px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"760\" height=\"1140\" data-id=\"29031\" src=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6362-I-760x1140.jpg\" alt=\"\" class=\"wp-image-29031\" srcset=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6362-I-760x1140.jpg 760w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6362-I-427x640.jpg 427w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6362-I-320x480.jpg 320w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6362-I-768x1152.jpg 768w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6362-I-1024x1536.jpg 1024w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6362-I-1365x2048.jpg 1365w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6362-I-960x1440.jpg 960w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6362-I-640x960.jpg 640w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6362-I-scaled.jpg 1707w\" sizes=\"(max-width: 760px) 100vw, 760px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1140\" height=\"760\" data-id=\"29028\" src=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6348-I-1140x760.jpg\" alt=\"\" class=\"wp-image-29028\" srcset=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6348-I-1140x760.jpg 1140w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6348-I-640x427.jpg 640w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6348-I-320x213.jpg 320w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6348-I-768x512.jpg 768w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6348-I-1536x1024.jpg 1536w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6348-I-2048x1366.jpg 2048w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6348-I-1440x960.jpg 1440w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6348-I-960x640.jpg 960w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"760\" height=\"1140\" data-id=\"29024\" src=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6345-I-760x1140.jpg\" alt=\"\" class=\"wp-image-29024\" srcset=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6345-I-760x1140.jpg 760w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6345-I-427x640.jpg 427w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6345-I-320x480.jpg 320w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6345-I-768x1152.jpg 768w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6345-I-1024x1536.jpg 1024w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6345-I-1365x2048.jpg 1365w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6345-I-960x1440.jpg 960w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6345-I-640x960.jpg 640w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6345-I-scaled.jpg 1707w\" sizes=\"(max-width: 760px) 100vw, 760px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"760\" height=\"1140\" data-id=\"29015\" src=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6833-I-760x1140.jpg\" alt=\"\" class=\"wp-image-29015\" srcset=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6833-I-760x1140.jpg 760w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6833-I-427x640.jpg 427w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6833-I-320x480.jpg 320w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6833-I-768x1152.jpg 768w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6833-I-1024x1536.jpg 1024w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6833-I-1365x2048.jpg 1365w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6833-I-960x1440.jpg 960w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6833-I-640x960.jpg 640w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6833-I-scaled.jpg 1707w\" sizes=\"(max-width: 760px) 100vw, 760px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"760\" height=\"1140\" data-id=\"29011\" src=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6826-I-760x1140.jpg\" alt=\"\" class=\"wp-image-29011\" srcset=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6826-I-760x1140.jpg 760w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6826-I-427x640.jpg 427w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6826-I-320x480.jpg 320w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6826-I-768x1152.jpg 768w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6826-I-1024x1536.jpg 1024w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6826-I-1365x2048.jpg 1365w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6826-I-960x1440.jpg 960w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6826-I-640x960.jpg 640w, https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6826-I-scaled.jpg 1707w\" sizes=\"(max-width: 760px) 100vw, 760px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/logo-dipta-cat.svg\" alt=\"\" class=\"wp-image-20371\"\/><\/figure>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/nataliaferre.com\/es\/blog\/\">Otras publicaciones<\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pretende dar valor a todos estos sitios hist\u00f3ricos de los nuestros pueblos, que fueron esenciales en su momento, y que es necesario preservar.<\/p>\n","protected":false},"author":1001,"featured_media":28999,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"inline_featured_image":false,"footnotes":""},"categories":[183],"tags":[],"class_list":["post-28549","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-entradas-del-blog","post_format-post-format-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lo Safreig. El Masroig, Els Rentadors - Nat\u00e0lia Ferr\u00e9 - Escultora, Ceramista, Pintora y Galerista<\/title>\n<meta name=\"description\" content=\"Pretende dar valor a todos estos sitios hist\u00f3ricos de los nuestros pueblos, que fueron esenciales en su momento, y que es necesario preservar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nataliaferre.com\/es\/lo-safreig\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo Safreig. El Masroig, Els Rentadors - Nat\u00e0lia Ferr\u00e9 - Escultora, Ceramista, Pintora y Galerista\" \/>\n<meta property=\"og:description\" content=\"Pretende dar valor a todos estos sitios hist\u00f3ricos de los nuestros pueblos, que fueron esenciales en su momento, y que es necesario preservar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nataliaferre.com\/es\/lo-safreig\/\" \/>\n<meta property=\"og:site_name\" content=\"Nat\u00e0lia Ferr\u00e9\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-30T11:14:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-28T09:32:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6546-I-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"SS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/lo-safreig\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/lo-safreig\\\/\"},\"author\":{\"name\":\"SS\",\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/#\\\/schema\\\/person\\\/d24812eff3de20c7fef258c73031211b\"},\"headline\":\"Lo Safreig. El Masroig, Els Rentadors\",\"datePublished\":\"2025-12-30T11:14:00+00:00\",\"dateModified\":\"2026-01-28T09:32:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/lo-safreig\\\/\"},\"wordCount\":73,\"publisher\":{\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/lo-safreig\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nataliaferre.com\\\/wp-content\\\/uploads\\\/0C1A6546-I-scaled.jpg\",\"articleSection\":[\"Entradas del blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/lo-safreig\\\/\",\"url\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/lo-safreig\\\/\",\"name\":\"Lo Safreig. El Masroig, Els Rentadors - Nat\u00e0lia Ferr\u00e9 - Escultora, Ceramista, Pintora y Galerista\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/lo-safreig\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/lo-safreig\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nataliaferre.com\\\/wp-content\\\/uploads\\\/0C1A6546-I-scaled.jpg\",\"datePublished\":\"2025-12-30T11:14:00+00:00\",\"dateModified\":\"2026-01-28T09:32:38+00:00\",\"description\":\"Pretende dar valor a todos estos sitios hist\u00f3ricos de los nuestros pueblos, que fueron esenciales en su momento, y que es necesario preservar.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/lo-safreig\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nataliaferre.com\\\/es\\\/lo-safreig\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/lo-safreig\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nataliaferre.com\\\/wp-content\\\/uploads\\\/0C1A6546-I-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/nataliaferre.com\\\/wp-content\\\/uploads\\\/0C1A6546-I-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/lo-safreig\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lo Safreig. El Masroig, Els Rentadors\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/\",\"name\":\"Nat\u00e0lia Ferr\u00e9\",\"description\":\"Escultora, Ceramista, Pintora y Galerista\",\"publisher\":{\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/#organization\",\"name\":\"Nat\u00e0lia Ferr\u00e9\",\"url\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nataliaferre.com\\\/wp-content\\\/uploads\\\/natalia-ferre-la-artista-04-b.jpg\",\"contentUrl\":\"https:\\\/\\\/nataliaferre.com\\\/wp-content\\\/uploads\\\/natalia-ferre-la-artista-04-b.jpg\",\"width\":1300,\"height\":730,\"caption\":\"Nat\u00e0lia Ferr\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/#\\\/schema\\\/person\\\/d24812eff3de20c7fef258c73031211b\",\"name\":\"SS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/24eef1985b26736df2d58f92e3d55b90870719d23aca5b368fe2796ae2d4fd01?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/24eef1985b26736df2d58f92e3d55b90870719d23aca5b368fe2796ae2d4fd01?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/24eef1985b26736df2d58f92e3d55b90870719d23aca5b368fe2796ae2d4fd01?s=96&d=mm&r=g\",\"caption\":\"SS\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo Safreig. El Masroig, Els Rentadors - Nat\u00e0lia Ferr\u00e9 - Escultora, Ceramista, Pintora y Galerista","description":"Pretende dar valor a todos estos sitios hist\u00f3ricos de los nuestros pueblos, que fueron esenciales en su momento, y que es necesario preservar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nataliaferre.com\/es\/lo-safreig\/","og_locale":"es_ES","og_type":"article","og_title":"Lo Safreig. El Masroig, Els Rentadors - Nat\u00e0lia Ferr\u00e9 - Escultora, Ceramista, Pintora y Galerista","og_description":"Pretende dar valor a todos estos sitios hist\u00f3ricos de los nuestros pueblos, que fueron esenciales en su momento, y que es necesario preservar.","og_url":"https:\/\/nataliaferre.com\/es\/lo-safreig\/","og_site_name":"Nat\u00e0lia Ferr\u00e9","article_published_time":"2025-12-30T11:14:00+00:00","article_modified_time":"2026-01-28T09:32:38+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6546-I-scaled.jpg","type":"image\/jpeg"}],"author":"SS","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"SS","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nataliaferre.com\/es\/lo-safreig\/#article","isPartOf":{"@id":"https:\/\/nataliaferre.com\/es\/lo-safreig\/"},"author":{"name":"SS","@id":"https:\/\/nataliaferre.com\/es\/#\/schema\/person\/d24812eff3de20c7fef258c73031211b"},"headline":"Lo Safreig. El Masroig, Els Rentadors","datePublished":"2025-12-30T11:14:00+00:00","dateModified":"2026-01-28T09:32:38+00:00","mainEntityOfPage":{"@id":"https:\/\/nataliaferre.com\/es\/lo-safreig\/"},"wordCount":73,"publisher":{"@id":"https:\/\/nataliaferre.com\/es\/#organization"},"image":{"@id":"https:\/\/nataliaferre.com\/es\/lo-safreig\/#primaryimage"},"thumbnailUrl":"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6546-I-scaled.jpg","articleSection":["Entradas del blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/nataliaferre.com\/es\/lo-safreig\/","url":"https:\/\/nataliaferre.com\/es\/lo-safreig\/","name":"Lo Safreig. El Masroig, Els Rentadors - Nat\u00e0lia Ferr\u00e9 - Escultora, Ceramista, Pintora y Galerista","isPartOf":{"@id":"https:\/\/nataliaferre.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nataliaferre.com\/es\/lo-safreig\/#primaryimage"},"image":{"@id":"https:\/\/nataliaferre.com\/es\/lo-safreig\/#primaryimage"},"thumbnailUrl":"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6546-I-scaled.jpg","datePublished":"2025-12-30T11:14:00+00:00","dateModified":"2026-01-28T09:32:38+00:00","description":"Pretende dar valor a todos estos sitios hist\u00f3ricos de los nuestros pueblos, que fueron esenciales en su momento, y que es necesario preservar.","breadcrumb":{"@id":"https:\/\/nataliaferre.com\/es\/lo-safreig\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nataliaferre.com\/es\/lo-safreig\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nataliaferre.com\/es\/lo-safreig\/#primaryimage","url":"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6546-I-scaled.jpg","contentUrl":"https:\/\/nataliaferre.com\/wp-content\/uploads\/0C1A6546-I-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/nataliaferre.com\/es\/lo-safreig\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/nataliaferre.com\/es\/"},{"@type":"ListItem","position":2,"name":"Lo Safreig. El Masroig, Els Rentadors"}]},{"@type":"WebSite","@id":"https:\/\/nataliaferre.com\/es\/#website","url":"https:\/\/nataliaferre.com\/es\/","name":"Nat\u00e0lia Ferr\u00e9","description":"Escultora, Ceramista, Pintora y Galerista","publisher":{"@id":"https:\/\/nataliaferre.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nataliaferre.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nataliaferre.com\/es\/#organization","name":"Nat\u00e0lia Ferr\u00e9","url":"https:\/\/nataliaferre.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nataliaferre.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nataliaferre.com\/wp-content\/uploads\/natalia-ferre-la-artista-04-b.jpg","contentUrl":"https:\/\/nataliaferre.com\/wp-content\/uploads\/natalia-ferre-la-artista-04-b.jpg","width":1300,"height":730,"caption":"Nat\u00e0lia Ferr\u00e9"},"image":{"@id":"https:\/\/nataliaferre.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/nataliaferre.com\/es\/#\/schema\/person\/d24812eff3de20c7fef258c73031211b","name":"SS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/24eef1985b26736df2d58f92e3d55b90870719d23aca5b368fe2796ae2d4fd01?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/24eef1985b26736df2d58f92e3d55b90870719d23aca5b368fe2796ae2d4fd01?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/24eef1985b26736df2d58f92e3d55b90870719d23aca5b368fe2796ae2d4fd01?s=96&d=mm&r=g","caption":"SS"}}]}},"_links":{"self":[{"href":"https:\/\/nataliaferre.com\/es\/wp-json\/wp\/v2\/posts\/28549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nataliaferre.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nataliaferre.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nataliaferre.com\/es\/wp-json\/wp\/v2\/users\/1001"}],"replies":[{"embeddable":true,"href":"https:\/\/nataliaferre.com\/es\/wp-json\/wp\/v2\/comments?post=28549"}],"version-history":[{"count":4,"href":"https:\/\/nataliaferre.com\/es\/wp-json\/wp\/v2\/posts\/28549\/revisions"}],"predecessor-version":[{"id":29693,"href":"https:\/\/nataliaferre.com\/es\/wp-json\/wp\/v2\/posts\/28549\/revisions\/29693"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nataliaferre.com\/es\/wp-json\/wp\/v2\/media\/28999"}],"wp:attachment":[{"href":"https:\/\/nataliaferre.com\/es\/wp-json\/wp\/v2\/media?parent=28549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nataliaferre.com\/es\/wp-json\/wp\/v2\/categories?post=28549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nataliaferre.com\/es\/wp-json\/wp\/v2\/tags?post=28549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}