{"id":9970,"date":"2021-11-20T12:00:30","date_gmt":"2021-11-20T11:00:30","guid":{"rendered":"https:\/\/nataliaferre.com\/?p=9970"},"modified":"2021-11-21T09:06:47","modified_gmt":"2021-11-21T08:06:47","slug":"slider-cursos-escultura","status":"publish","type":"post","link":"https:\/\/nataliaferre.com\/es\/slider-cursos-escultura\/","title":{"rendered":"Aprende escultura en cer\u00e1mica"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":999,"featured_media":9319,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[133],"tags":[],"class_list":["post-9970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slider-pagina-de-inicio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u2014<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u2014\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nataliaferre.com\/es\/slider-cursos-escultura\/\" \/>\n<meta property=\"og:site_name\" content=\"Nat\u00e0lia Ferr\u00e9\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-20T11:00:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-21T08:06:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nataliaferre.com\/wp-content\/uploads\/galeria-natalia-ferre-la-galeria-08.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"835\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Idel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Idel\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/slider-cursos-escultura\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/slider-cursos-escultura\\\/\"},\"author\":{\"name\":\"Idel\",\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/#\\\/schema\\\/person\\\/62ace9fa3e2f4f9850bd3151aa36dfb9\"},\"headline\":\"Aprende escultura en cer\u00e1mica\",\"datePublished\":\"2021-11-20T11:00:30+00:00\",\"dateModified\":\"2021-11-21T08:06:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/slider-cursos-escultura\\\/\"},\"wordCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/slider-cursos-escultura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nataliaferre.com\\\/wp-content\\\/uploads\\\/galeria-natalia-ferre-la-galeria-08.jpg\",\"articleSection\":[\"Slider p\u00e1gina de inicio\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/slider-cursos-escultura\\\/\",\"url\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/slider-cursos-escultura\\\/\",\"name\":\"\u2014\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/slider-cursos-escultura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/slider-cursos-escultura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nataliaferre.com\\\/wp-content\\\/uploads\\\/galeria-natalia-ferre-la-galeria-08.jpg\",\"datePublished\":\"2021-11-20T11:00:30+00:00\",\"dateModified\":\"2021-11-21T08:06:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/slider-cursos-escultura\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nataliaferre.com\\\/es\\\/slider-cursos-escultura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/slider-cursos-escultura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nataliaferre.com\\\/wp-content\\\/uploads\\\/galeria-natalia-ferre-la-galeria-08.jpg\",\"contentUrl\":\"https:\\\/\\\/nataliaferre.com\\\/wp-content\\\/uploads\\\/galeria-natalia-ferre-la-galeria-08.jpg\",\"width\":835,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/slider-cursos-escultura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aprende escultura en cer\u00e1mica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/\",\"name\":\"Nat\u00e0lia Ferr\u00e9\",\"description\":\"Escultora, Ceramista, Pintora y Galerista\",\"publisher\":{\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/#organization\",\"name\":\"Nat\u00e0lia Ferr\u00e9\",\"url\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nataliaferre.com\\\/wp-content\\\/uploads\\\/natalia-ferre-la-artista-04-b.jpg\",\"contentUrl\":\"https:\\\/\\\/nataliaferre.com\\\/wp-content\\\/uploads\\\/natalia-ferre-la-artista-04-b.jpg\",\"width\":1300,\"height\":730,\"caption\":\"Nat\u00e0lia Ferr\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nataliaferre.com\\\/es\\\/#\\\/schema\\\/person\\\/62ace9fa3e2f4f9850bd3151aa36dfb9\",\"name\":\"Idel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c41eef29cc53bb1b85862458bd8af3b680c7b6f5b495f6ed686ca9ec6bc4f08?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c41eef29cc53bb1b85862458bd8af3b680c7b6f5b495f6ed686ca9ec6bc4f08?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c41eef29cc53bb1b85862458bd8af3b680c7b6f5b495f6ed686ca9ec6bc4f08?s=96&d=mm&r=g\",\"caption\":\"Idel\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u2014","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"\u2014","og_url":"https:\/\/nataliaferre.com\/es\/slider-cursos-escultura\/","og_site_name":"Nat\u00e0lia Ferr\u00e9","article_published_time":"2021-11-20T11:00:30+00:00","article_modified_time":"2021-11-21T08:06:47+00:00","og_image":[{"width":835,"height":960,"url":"https:\/\/nataliaferre.com\/wp-content\/uploads\/galeria-natalia-ferre-la-galeria-08.jpg","type":"image\/jpeg"}],"author":"Idel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Idel"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nataliaferre.com\/es\/slider-cursos-escultura\/#article","isPartOf":{"@id":"https:\/\/nataliaferre.com\/es\/slider-cursos-escultura\/"},"author":{"name":"Idel","@id":"https:\/\/nataliaferre.com\/es\/#\/schema\/person\/62ace9fa3e2f4f9850bd3151aa36dfb9"},"headline":"Aprende escultura en cer\u00e1mica","datePublished":"2021-11-20T11:00:30+00:00","dateModified":"2021-11-21T08:06:47+00:00","mainEntityOfPage":{"@id":"https:\/\/nataliaferre.com\/es\/slider-cursos-escultura\/"},"wordCount":5,"publisher":{"@id":"https:\/\/nataliaferre.com\/es\/#organization"},"image":{"@id":"https:\/\/nataliaferre.com\/es\/slider-cursos-escultura\/#primaryimage"},"thumbnailUrl":"https:\/\/nataliaferre.com\/wp-content\/uploads\/galeria-natalia-ferre-la-galeria-08.jpg","articleSection":["Slider p\u00e1gina de inicio"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/nataliaferre.com\/es\/slider-cursos-escultura\/","url":"https:\/\/nataliaferre.com\/es\/slider-cursos-escultura\/","name":"\u2014","isPartOf":{"@id":"https:\/\/nataliaferre.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nataliaferre.com\/es\/slider-cursos-escultura\/#primaryimage"},"image":{"@id":"https:\/\/nataliaferre.com\/es\/slider-cursos-escultura\/#primaryimage"},"thumbnailUrl":"https:\/\/nataliaferre.com\/wp-content\/uploads\/galeria-natalia-ferre-la-galeria-08.jpg","datePublished":"2021-11-20T11:00:30+00:00","dateModified":"2021-11-21T08:06:47+00:00","breadcrumb":{"@id":"https:\/\/nataliaferre.com\/es\/slider-cursos-escultura\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nataliaferre.com\/es\/slider-cursos-escultura\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nataliaferre.com\/es\/slider-cursos-escultura\/#primaryimage","url":"https:\/\/nataliaferre.com\/wp-content\/uploads\/galeria-natalia-ferre-la-galeria-08.jpg","contentUrl":"https:\/\/nataliaferre.com\/wp-content\/uploads\/galeria-natalia-ferre-la-galeria-08.jpg","width":835,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/nataliaferre.com\/es\/slider-cursos-escultura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/nataliaferre.com\/es\/"},{"@type":"ListItem","position":2,"name":"Aprende escultura en cer\u00e1mica"}]},{"@type":"WebSite","@id":"https:\/\/nataliaferre.com\/es\/#website","url":"https:\/\/nataliaferre.com\/es\/","name":"Nat\u00e0lia Ferr\u00e9","description":"Escultora, Ceramista, Pintora y Galerista","publisher":{"@id":"https:\/\/nataliaferre.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nataliaferre.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nataliaferre.com\/es\/#organization","name":"Nat\u00e0lia Ferr\u00e9","url":"https:\/\/nataliaferre.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nataliaferre.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nataliaferre.com\/wp-content\/uploads\/natalia-ferre-la-artista-04-b.jpg","contentUrl":"https:\/\/nataliaferre.com\/wp-content\/uploads\/natalia-ferre-la-artista-04-b.jpg","width":1300,"height":730,"caption":"Nat\u00e0lia Ferr\u00e9"},"image":{"@id":"https:\/\/nataliaferre.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/nataliaferre.com\/es\/#\/schema\/person\/62ace9fa3e2f4f9850bd3151aa36dfb9","name":"Idel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5c41eef29cc53bb1b85862458bd8af3b680c7b6f5b495f6ed686ca9ec6bc4f08?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c41eef29cc53bb1b85862458bd8af3b680c7b6f5b495f6ed686ca9ec6bc4f08?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c41eef29cc53bb1b85862458bd8af3b680c7b6f5b495f6ed686ca9ec6bc4f08?s=96&d=mm&r=g","caption":"Idel"}}]}},"_links":{"self":[{"href":"https:\/\/nataliaferre.com\/es\/wp-json\/wp\/v2\/posts\/9970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nataliaferre.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nataliaferre.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nataliaferre.com\/es\/wp-json\/wp\/v2\/users\/999"}],"replies":[{"embeddable":true,"href":"https:\/\/nataliaferre.com\/es\/wp-json\/wp\/v2\/comments?post=9970"}],"version-history":[{"count":0,"href":"https:\/\/nataliaferre.com\/es\/wp-json\/wp\/v2\/posts\/9970\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nataliaferre.com\/es\/wp-json\/wp\/v2\/media\/9319"}],"wp:attachment":[{"href":"https:\/\/nataliaferre.com\/es\/wp-json\/wp\/v2\/media?parent=9970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nataliaferre.com\/es\/wp-json\/wp\/v2\/categories?post=9970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nataliaferre.com\/es\/wp-json\/wp\/v2\/tags?post=9970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}